{"id":784,"date":"2021-08-26T14:57:26","date_gmt":"2021-08-26T12:57:26","guid":{"rendered":"http:\/\/rr.fwch.pl\/?page_id=784"},"modified":"2023-12-01T16:52:14","modified_gmt":"2023-12-01T15:52:14","slug":"company","status":"publish","type":"page","link":"https:\/\/delipop.fwch.pl\/fr\/company\/","title":{"rendered":"Entreprise"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"784\" class=\"elementor elementor-784\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f7e23b9 elementor-section-stretched accordion-section elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"f7e23b9\" data-element_type=\"section\" id=\"accord4\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0e38ed0\" data-id=\"0e38ed0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-bf9b6a8 elementor-section-full_width elementor-section-content-middle elementor-section-height-default elementor-section-height-default\" data-id=\"bf9b6a8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0f7d177\" data-id=\"0f7d177\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a0ef776 elementor-widget elementor-widget-heading\" data-id=\"a0ef776\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Participez<br \/>\n\u00e0 la r\u00e9volution<br \/>\n<span class=\"dark-color\">de la livraison<br \/>\ne-commerce<\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-006ec66 elementor-align-center elementor-mobile-align-justify btn-primary-dark elementor-widget elementor-widget-button\" data-id=\"006ec66\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"\/fr\/sustainability\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">D\u00e9veloppement durable \u2192<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec57e3b elementor-align-center elementor-mobile-align-justify btn-primary-dark elementor-widget elementor-widget-button\" data-id=\"ec57e3b\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"\/fr\/career\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Carri\u00e8re \u2192<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-67a6c91 animateHole animateO\" data-id=\"67a6c91\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c5ca8a animate-img elementor-widget elementor-widget-image\" data-id=\"9c5ca8a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"719\" src=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/03\/Mask-Group-29a@2x-768x719.png\" class=\"attachment-medium_large size-medium_large wp-image-6679\" alt=\"\" srcset=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/03\/Mask-Group-29a@2x-768x719.png 768w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/03\/Mask-Group-29a@2x-300x281.png 300w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/03\/Mask-Group-29a@2x-1024x959.png 1024w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/03\/Mask-Group-29a@2x-13x12.png 13w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/03\/Mask-Group-29a@2x.png 1165w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/03\/Mask-Group-29a@2x-300x281@2x.png 600w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/03\/Mask-Group-29a@2x-13x12@2x.png 26w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-409b057 showLeft paris1 elementor-widget elementor-widget-image\" data-id=\"409b057\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/elementor\/thumbs\/Group-1351@2x-pmmp2iczuwu8gcpwrd0dkazf9mrp7ym98i0zj7y5y6.png\" title=\"Group 1351@2x\" alt=\"Group 1351@2x\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5266631 showRight paris2 elementor-widget elementor-widget-image\" data-id=\"5266631\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/elementor\/thumbs\/Group-1352@2x-pmmp2hf5o2sy4qr9wulqzt7yo8wc09iiwddi1xzjfy.png\" title=\"Group 1352@2x\" alt=\"Group 1352@2x\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c9fabbf elementor-section-height-min-height elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"c9fabbf\" data-element_type=\"section\" id=\"grocery-video\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5e847e7\" data-id=\"5e847e7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-41f7bda elementor-widget elementor-widget-spacer\" data-id=\"41f7bda\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-47cde4b elementor-widget elementor-widget-heading\" data-id=\"47cde4b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"elementor-heading-title elementor-size-default elementor-inline-editing pen\" data-elementor-setting-key=\"title\" data-pen-placeholder=\"Pisz tutaj...\" style=\"font-weight: var(--h2FontWeight)\">D\u00c9COUVREZ EN IMAGES <\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f5b5b9e elementor-widget elementor-widget-heading\" data-id=\"f5b5b9e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"elementor-heading-title elementor-size-default elementor-inline-editing pen\" data-elementor-setting-key=\"title\" data-pen-placeholder=\"Pisz tutaj...\" style=\"font-weight: var(--h2FontWeight)\">LE TOUT 1ER POINT DE RETRAIT DELIPOP<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d466d9 elementor-widget elementor-widget-heading\" data-id=\"7d466d9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\"><br \/><\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bed6d06 elementor-widget__width-initial elementor-widget elementor-widget-video\" data-id=\"bed6d06\" data-element_type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;hosted&quot;,&quot;show_image_overlay&quot;:&quot;yes&quot;,&quot;image_overlay&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/delipop.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/vlcsnap-2021-10-05-23h34m33s676a.png&quot;,&quot;id&quot;:3280,&quot;size&quot;:&quot;&quot;,&quot;alt&quot;:&quot;&quot;,&quot;source&quot;:&quot;library&quot;},&quot;controls&quot;:&quot;yes&quot;}\" data-no-translation=\"\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>.elementor-element-bed6d06{display:none !important}<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af7f2ad elementor-widget__width-initial vid-col elementor-widget elementor-widget-video\" data-id=\"af7f2ad\" data-element_type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;hosted&quot;,&quot;show_image_overlay&quot;:&quot;yes&quot;,&quot;image_overlay&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/delipop.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/vlcsnap-2021-10-05-23h34m33s676a.png&quot;,&quot;id&quot;:3280,&quot;size&quot;:&quot;&quot;,&quot;alt&quot;:&quot;&quot;,&quot;source&quot;:&quot;library&quot;},&quot;controls&quot;:&quot;yes&quot;}\" data-no-translation=\"\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-hosted-video elementor-wrapper elementor-open-inline\">\n\t\t\t\t\t<video class=\"elementor-video\" src=\"\/wp-content\/uploads\/2021\/10\/Delipop-Paris-Oppening-Fr+Lower_Thirds+Subtitles-1.mp4\" controls=\"\" preload=\"metadata\" controlslist=\"nodownload\"><\/video>\n\t\t\t\t\t\t<div class=\"elementor-custom-embed-image-overlay\" style=\"background-image: url(https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2021\/10\/vlcsnap-2021-10-05-23h34m33s676a-768x432.png);\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-custom-embed-play\" role=\"button\" aria-label=\"Lire la vid\u00e9o\" tabindex=\"0\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-play\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ed7b7ce elementor-section-height-min-height elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"ed7b7ce\" data-element_type=\"section\" id=\"network\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-da4cb5a\" data-id=\"da4cb5a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c12f5be elementor-widget elementor-widget-spacer\" data-id=\"c12f5be\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b91ae74 elementor-widget elementor-widget-heading\" data-id=\"b91ae74\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">DELIPOP EST UN R\u00c9SEAU <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0a86f6e elementor-widget elementor-widget-heading\" data-id=\"0a86f6e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">DE POINTS DE RETRAIT MULTIMARCHANDS\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3183ff0 elementor-widget elementor-widget-heading\" data-id=\"3183ff0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">d\u00e9couvrez les avantages de notre solution : <\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a78b4fd elementor-section-height-min-height elementor-section-stretched elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"a78b4fd\" data-element_type=\"section\" id=\"e-grocery\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9364549\" data-id=\"9364549\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-58ef30d elementor-section-full_width elementor-reverse-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"58ef30d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0cbd258\" data-id=\"0cbd258\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d070d10 elementor-widget elementor-widget-spacer\" data-id=\"d070d10\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-08493fa elementor-widget elementor-widget-heading\" data-id=\"08493fa\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default translation-block\">Rejoignez Delipop<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0a6241a elementor-widget elementor-widget-heading\" data-id=\"0a6241a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default translation-block\">et Soyez Acteur de l'Innovation!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f57a17e elementor-widget elementor-widget-text-editor\" data-id=\"f57a17e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Chez Delipop, nous sommes bien plus qu'une entreprise de distribution alimentaire. Nous sommes des pionniers de l'innovation, des d\u00e9fenseurs de la durabilit\u00e9 et des cr\u00e9ateurs de changement. Si vous recherchez une carri\u00e8re qui a un impact r\u00e9el sur les villes de demain, ne cherchez pas plus loin.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e031fe3 elementor-align-center elementor-mobile-align-justify btn-primary-dark elementor-widget elementor-widget-button\" data-id=\"e031fe3\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"#e-grocery\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Je suis un detaillant \u2192<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6927b0f elementor-align-center elementor-mobile-align-justify btn-primary-dark elementor-widget elementor-widget-button\" data-id=\"6927b0f\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"#rent-us-space\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Postuler \u2192<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6dededc animateHole animateO\" data-id=\"6dededc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-856c450 animate-img elementor-widget elementor-widget-image\" data-id=\"856c450\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"809\" src=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/02\/Mask-Group-26a@2x-768x809.png\" class=\"attachment-medium_large size-medium_large wp-image-6218\" alt=\"\" srcset=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/02\/Mask-Group-26a@2x-768x809.png 768w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/02\/Mask-Group-26a@2x-285x300.png 285w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/02\/Mask-Group-26a@2x-11x12.png 11w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/02\/Mask-Group-26a@2x.png 954w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/02\/Mask-Group-26a@2x-285x300@2x.png 570w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/02\/Mask-Group-26a@2x-11x12@2x.png 22w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-65e6431 eye elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"65e6431\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"390\" height=\"321\" src=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/02\/Group-1392@2x.png\" class=\"attachment-medium_large size-medium_large wp-image-6219\" alt=\"\" srcset=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/02\/Group-1392@2x.png 390w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/02\/Group-1392@2x-300x247.png 300w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/02\/Group-1392@2x-15x12.png 15w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/02\/Group-1392@2x-15x12@2x.png 30w\" sizes=\"(max-width: 390px) 100vw, 390px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b50a6aa eye elementor-widget elementor-widget-image\" data-id=\"b50a6aa\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/elementor\/thumbs\/Group-1626c@2x-prbdtmshk32vkrtgoo0iet7wlsyzw98y7idlm3ymdi.png\" title=\"Group 1626c@2x\" alt=\"Group 1626c@2x\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7527f54 eye elementor-widget elementor-widget-image\" data-id=\"7527f54\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/elementor\/thumbs\/Group-1626a@2x-prbdep4syumv3tifw7lwskw8tel1ldyhhl7v3u3t8m.png\" title=\"Group 1626a@2x\" alt=\"Group 1626a@2x\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22d2d3c blinking elementor-widget elementor-widget-html\" data-id=\"22d2d3c\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<?xml version=\"1.0\" encoding=\"utf-8\"?>\r\n<!-- Generator: Adobe Illustrator 16.0.0, SVG Export Plug-In . SVG Version: 6.00 Build 0)  -->\r\n<!DOCTYPE svg PUBLIC \"-\/\/W3C\/\/DTD SVG 1.1\/\/EN\" \"http:\/\/www.w3.org\/Graphics\/SVG\/1.1\/DTD\/svg11.dtd\">\r\n<svg version=\"1.1\" id=\"Warstwa_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\r\n\t width=\"162px\" height=\"115px\" viewbox=\"0 0 327 234\" style=\"enable-background:new 0 0 327 234;\" xml:space=\"preserve\">\r\n<style type=\"text\/css\">\r\n\r\n\t.st0{opacity:0;fill:#FFEB3E;}\r\n\t.st1{fill:#FFEB3E;}\r\n\r\n<\/style>\r\n<path id=\"closed\" transform=\"translate(163, 117)\" class=\"st0\" d=\"M-163.5,0C-137.6-60.5-72-117,0-117S141.9-60,163.5,0C143.9,59.4,72,117,0,117\tC-70.5,117-140,60-163.5,0z\">\r\n<\/path>\r\n<path id=\"open\" transform=\"translate(163, 117)\" class=\"st1\" d=\"M-163.5,0C-137.6-60.5-72-117,0-117S141.9-60,163.5,0C132.6-51.3,72-95,0-95\tC-70.5-95-134.8-46.7-163.5,0z\"\/>\r\n<\/svg>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-325adb9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"325adb9\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1788d31\" data-id=\"1788d31\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8fdfecb elementor-widget elementor-widget-spacer\" data-id=\"8fdfecb\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-695e739 elementor-widget elementor-widget-heading\" data-id=\"695e739\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">QUI<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-10b606c elementor-widget elementor-widget-heading\" data-id=\"10b606c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">SOMMES NOUS ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c41c5f6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c41c5f6\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b446abc\" data-id=\"b446abc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-71c07c9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"71c07c9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f195651\" data-id=\"f195651\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0220df6 rent-slider elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"0220df6\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;dots&quot;,&quot;infinite&quot;:&quot;no&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrousel d\u2019images\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 sur 9\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"0220df6\" data-elementor-lightbox-title=\"194 Av de Versailles 75016 Paris\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzkyOCwidXJsIjoiaHR0cHM6XC9cL2RlbGlwb3AuZndjaC5wbFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMTJcLzIwMjEwOTIwXzE1MjYzMl9meHRvdGVtMi5qcGciLCJzbGlkZXNob3ciOiIwMjIwZGY2In0%3D\" href=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2021\/12\/20210920_152632_fxtotem2.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2021\/12\/20210920_152632_fxtotem2-930x620.jpg\" alt=\"194 Av de Versailles 75016 Paris\" \/><figcaption class=\"elementor-image-carousel-caption\">194 Av de Versailles 75016 Paris<\/figcaption><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 sur 9\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"0220df6\" data-elementor-lightbox-title=\"194 Av de Versailles 75016 Paris\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjM1NywidXJsIjoiaHR0cHM6XC9cL2RlbGlwb3AuZndjaC5wbFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMTBcLzIwMjEwOTIxXzEzMDk1Ml9meDIucG5nIiwic2xpZGVzaG93IjoiMDIyMGRmNiJ9\" href=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2021\/10\/20210921_130952_fx2.png\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2021\/10\/20210921_130952_fx2-930x620.png\" alt=\"194 Av de Versailles 75016 Paris\" \/><figcaption class=\"elementor-image-carousel-caption\">194 Av de Versailles 75016 Paris<\/figcaption><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 sur 9\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"0220df6\" data-elementor-lightbox-title=\"194 Av de Versailles 75016 Paris\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjM1OCwidXJsIjoiaHR0cHM6XC9cL2RlbGlwb3AuZndjaC5wbFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMTBcLzIwMjEwOTIxXzEzMTExNl9meDIucG5nIiwic2xpZGVzaG93IjoiMDIyMGRmNiJ9\" href=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2021\/10\/20210921_131116_fx2.png\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2021\/10\/20210921_131116_fx2-930x620.png\" alt=\"194 Av de Versailles 75016 Paris\" \/><figcaption class=\"elementor-image-carousel-caption\">194 Av de Versailles 75016 Paris<\/figcaption><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 sur 9\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"0220df6\" data-elementor-lightbox-title=\"194 Av de Versailles 75016 Paris\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjM1OSwidXJsIjoiaHR0cHM6XC9cL2RlbGlwb3AuZndjaC5wbFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMTBcLzIwMjEwOTIxXzEzMTEzMF9meDIucG5nIiwic2xpZGVzaG93IjoiMDIyMGRmNiJ9\" href=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2021\/10\/20210921_131130_fx2.png\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2021\/10\/20210921_131130_fx2-930x620.png\" alt=\"194 Av de Versailles 75016 Paris\" \/><figcaption class=\"elementor-image-carousel-caption\">194 Av de Versailles 75016 Paris<\/figcaption><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 sur 9\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"0220df6\" data-elementor-lightbox-title=\"194 Av de Versailles 75016 Paris\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjM2MCwidXJsIjoiaHR0cHM6XC9cL2RlbGlwb3AuZndjaC5wbFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMTBcLzIwMjEwOTIxXzEzMTMyOF9meDIucG5nIiwic2xpZGVzaG93IjoiMDIyMGRmNiJ9\" href=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2021\/10\/20210921_131328_fx2.png\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2021\/10\/20210921_131328_fx2-930x620.png\" alt=\"194 Av de Versailles 75016 Paris\" \/><figcaption class=\"elementor-image-carousel-caption\">194 Av de Versailles 75016 Paris<\/figcaption><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 sur 9\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"0220df6\" data-elementor-lightbox-title=\"194 Av de Versailles 75016 Paris\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjM2MSwidXJsIjoiaHR0cHM6XC9cL2RlbGlwb3AuZndjaC5wbFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMTBcLzIwMjEwOTIxXzIxMTIyM19meDIuanBnIiwic2xpZGVzaG93IjoiMDIyMGRmNiJ9\" href=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2021\/10\/20210921_211223_fx2.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2021\/10\/20210921_211223_fx2-900x620.jpg\" alt=\"194 Av de Versailles 75016 Paris\" \/><figcaption class=\"elementor-image-carousel-caption\">194 Av de Versailles 75016 Paris<\/figcaption><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 sur 9\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"0220df6\" data-elementor-lightbox-title=\"bezons_www\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Njg5NCwidXJsIjoiaHR0cHM6XC9cL2RlbGlwb3AuZndjaC5wbFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDRcL2Jlem9uc193d3ctc2NhbGVkLmpwZyIsInNsaWRlc2hvdyI6IjAyMjBkZjYifQ%3D%3D\" href=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/04\/bezons_www-scaled.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/04\/bezons_www-930x620.jpg\" alt=\"ZAC Coeur de Ville 95870 Bezons\" \/><figcaption class=\"elementor-image-carousel-caption\">ZAC Coeur de Ville 95870 Bezons<\/figcaption><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 sur 9\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"0220df6\" data-elementor-lightbox-title=\"IMG_4845\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Njg5OCwidXJsIjoiaHR0cHM6XC9cL2RlbGlwb3AuZndjaC5wbFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDRcL0lNR180ODQ1LXNjYWxlZC5qcGciLCJzbGlkZXNob3ciOiIwMjIwZGY2In0%3D\" href=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/04\/IMG_4845-scaled.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/04\/IMG_4845-930x620.jpg\" alt=\"2 rue d&#039;Orsel 75018 Paris\" \/><figcaption class=\"elementor-image-carousel-caption\">2 rue d'Orsel 75018 Paris<\/figcaption><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 sur 9\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"0220df6\" data-elementor-lightbox-title=\"IMG_4849\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Njg5OSwidXJsIjoiaHR0cHM6XC9cL2RlbGlwb3AuZndjaC5wbFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDRcL0lNR180ODQ5LXNjYWxlZC5qcGciLCJzbGlkZXNob3ciOiIwMjIwZGY2In0%3D\" href=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/04\/IMG_4849-scaled.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/04\/IMG_4849-930x620.jpg\" alt=\"2 rue d&#039;Orsel 75018 Paris\" \/><figcaption class=\"elementor-image-carousel-caption\">2 rue d'Orsel 75018 Paris<\/figcaption><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ebb69c3 elementor-align-center elementor-mobile-align-justify elementor-hidden-desktop elementor-hidden-tablet btn-primary-dark elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"ebb69c3\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contact us<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f3cb928\" data-id=\"f3cb928\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a15c717 elementor-widget elementor-widget-text-editor\" data-id=\"a15c717\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Delipop est le premier R\u00e9seau Universel enti\u00e8rement automatis\u00e9 de points de retrait pour le e-commerce alimentaire. Il est enti\u00e8rement mutualis\u00e9 - au service de plusieurs marques de retailers.<\/p><p>Il a \u00e9t\u00e9 cr\u00e9\u00e9 pour r\u00e9pondre  \u00e0  la  demande croissante  de l\u2019e-commerce alimentaire et de donner aux clients la meilleure exp\u00e9rience possible, et apporter des solutions vertueuses et \u00e9cologiques pour les villes.<\/p><p>DFR propose \u00e0 ses partenaires Retailers, une solution de service bas\u00e9e sur la consolidation des flux de commandes E-commerce alimentaire sur des entrep\u00f4ts situ\u00e9s extra muros, et sur la livraison des points de retrait en zone urbaine, commun\u00e9ment appel\u00e9s \u00ab Drive Pi\u00e9ton \u00bb.<\/p><p>Les points Delipops sont \u00e9quip\u00e9s d\u2019un syst\u00e8me de remise de commandes totalement automatis\u00e9 qui permet aux clients de nos partenaires de venir collecter leurs courses alimentaires sur des cr\u00e9neaux qu\u2019ils choisissent 7 jours sur 7 et 24 heures sur 24.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b299d47 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b299d47\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-2765e65\" data-id=\"2765e65\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e8b03b1 elementor-widget elementor-widget-text-editor\" data-id=\"e8b03b1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5><span style=\"font-weight: 400;\">Delipop vise \u00e0 donner le pouvoir aux consommateurs en rendant les courses alimentaires plus faciles dans la vie de tous les jours sur la base de plusieurs valeurs :\u00a0<\/span><\/h5><h3><span style=\"font-weight: 400;\">Toujours disponible <\/span><\/h3><h5><span style=\"font-weight: 400;\">Nos points de retrait sont ouverts t\u00f4t le matin jusqu\u2019\u00e0 tard le soir (certains 24\/24) du lundi au dimanche. Les utilisateurs peuvent choisir le cr\u00e9neau horaire qui leur convient le mieux.<\/span><\/h5><h3><span style=\"font-weight: 400;\">Retrait simplifi\u00e9<\/span><\/h3><h5><span style=\"font-weight: 400;\">Les consommateurs peuvent r\u00e9cup\u00e9rer leurs courses facilement, sans effort, gr\u00e2ce \u00e0 un processus intuitif. <\/span><span style=\"font-weight: 400;\">Nous avons ajout\u00e9 une touche de magie en utilisant des sons ambiants, des lumi\u00e8res, des couleurs et m\u00eame des odeurs - pour guider les clients et cr\u00e9er une pause agr\u00e9able dans leur vie.<\/span><\/h5><h3><span style=\"font-weight: 400;\">Toujours frais<\/span><\/h3><h5><span style=\"font-weight: 400;\">Nos machines sont con\u00e7ues pour conserver les aliments au frais ou surgel\u00e9s \u2013 aussi frais que s\u2019ils avaient \u00e9t\u00e9 achet\u00e9s dans des magasins traditionnels.\u00a0<\/span><\/h5><h3><span style=\"font-weight: 400;\">\u00c9cologique<\/span><\/h3><h5><span style=\"font-weight: 400;\">(d\u00e9crite ci-dessous) - le plaisir de sauver la plan\u00e8te.<\/span><\/h5><h3><span style=\"font-weight: 400;\">Sans contraintes<\/span><\/h3><h5><span style=\"font-weight: 400;\">Gr\u00e2ce \u00e0 notre solution qui simplifie les courses alimentaires, les consommateurs peuvent avoir davantage de temps pour faire ce qu\u2019ils aiment et profiter davantage de leur ville.\u00a0<\/span><\/h5><h3><span style=\"font-weight: 400;\">Offre large<\/span><\/h3><h5>Les clients ont acc\u00e8s \u00e0 100 000 r\u00e9f\u00e9rences de d\u00e9taillants diversifi\u00e9s. Tout cela \u00e0 une distance de marche ou de v\u00e9lo.<\/h5><h3><span style=\"font-weight: 400;\">Autres aspects sociaux<\/span><\/h3><h5><span style=\"font-weight: 400;\">En outre, gr\u00e2ce \u00e0 la baisse des co\u00fbts de livraison, les grands acteurs du march\u00e9 de la distribution peuvent proposer aux habitants urbains des produits alimentaires aux prix les plus bas, ce qui est important dans les zones rurales o\u00f9 l'offre est souvent limit\u00e9e et tr\u00e8s ch\u00e8re.\n\nNotre solution permet de redynamiser un quartier et d'amener une offre de type hyper au pied des immeubles. Cela permet d'\u00e9viter aux habitants de prendre leur voiture pour aller faire les courses en banlieue dans les grands magasins.<\/span><\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2bd248f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2bd248f\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0d76d21\" data-id=\"0d76d21\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1231ac6 elementor-widget elementor-widget-heading\" data-id=\"1231ac6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-xl\">NOTRE INNOVATION<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d048812 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d048812\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a9b17cf\" data-id=\"a9b17cf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-998a4c0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"998a4c0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3edc5bf\" data-id=\"3edc5bf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2095240 elementor-widget elementor-widget-video\" data-id=\"2095240\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=3Z25WCUqZjM&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b796e62\" data-id=\"b796e62\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-240eb59 elementor-widget elementor-widget-text-editor\" data-id=\"240eb59\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5><span style=\"font-weight: 400;\">L\u2019e-commerce alimentaire est en plein essor mais les mod\u00e8les op\u00e9rationnels actuels ne peuvent proposer des solutions p\u00e9rennes assurant la profitabilit\u00e9 et la capacit\u00e9 de production aux retailers.\u00a0<\/span><\/h5><h5><span style=\"font-weight: 400;\">Nous devons \u00e9galement satisfaire les besoins des clients, qui recherchent des solutions pratiques, rapides et adapt\u00e9es \u00e0 leur vie.<\/span><\/h5><h5><span style=\"font-weight: 400;\">Et nous devons r\u00e9pondre \u00e0 l'\u00e9volut<\/span><span style=\"font-weight: 400;\">ion des villes et rechercher des mod\u00e8les qui r\u00e9duisent le trafic et aident l'environnemen<\/span><span style=\"font-weight: 400;\">t.<\/span><\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e4379ed elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e4379ed\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1ef4ea7\" data-id=\"1ef4ea7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-83980b3 elementor-widget elementor-widget-spacer\" data-id=\"83980b3\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f571c8e elementor-widget elementor-widget-image\" data-id=\"f571c8e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/01\/slide-4-1024x576.jpg\" class=\"attachment-large size-large wp-image-4788\" alt=\"\" srcset=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/01\/slide-4-1024x576.jpg 1024w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/01\/slide-4-300x169.jpg 300w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/01\/slide-4-768x432.jpg 768w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/01\/slide-4-1536x864.jpg 1536w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/01\/slide-4-18x10.jpg 18w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/01\/slide-4.jpg 1920w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/01\/slide-4-300x169@2x.jpg 600w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/01\/slide-4-18x10@2x.jpg 36w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-98b2a90 elementor-widget elementor-widget-spacer\" data-id=\"98b2a90\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-82977f4 elementor-widget elementor-widget-image\" data-id=\"82977f4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/01\/slide-3-1024x576.jpg\" class=\"attachment-large size-large wp-image-4785\" alt=\"\" srcset=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/01\/slide-3-1024x576.jpg 1024w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/01\/slide-3-300x169.jpg 300w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/01\/slide-3-768x432.jpg 768w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/01\/slide-3-1536x864.jpg 1536w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/01\/slide-3-18x10.jpg 18w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/01\/slide-3.jpg 1920w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/01\/slide-3-300x169@2x.jpg 600w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/01\/slide-3-18x10@2x.jpg 36w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e132de elementor-widget elementor-widget-spacer\" data-id=\"9e132de\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7dde69b elementor-widget elementor-widget-image\" data-id=\"7dde69b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/01\/slide-2-1024x576.jpg\" class=\"attachment-large size-large wp-image-4784\" alt=\"\" srcset=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/01\/slide-2-1024x576.jpg 1024w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/01\/slide-2-300x169.jpg 300w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/01\/slide-2-768x432.jpg 768w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/01\/slide-2-1536x864.jpg 1536w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/01\/slide-2-18x10.jpg 18w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/01\/slide-2.jpg 1920w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/01\/slide-2-300x169@2x.jpg 600w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/01\/slide-2-18x10@2x.jpg 36w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-48e0f36\" data-id=\"48e0f36\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ead4f7b elementor-widget elementor-widget-text-editor\" data-id=\"ead4f7b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5><span style=\"font-weight: 400;\">Delipop rel\u00e8ve tous ces d\u00e9fis en s'appuyant sur 5 piliers :<\/span><\/h5><h5><span style=\"font-weight: 400;\"><strong>1. Automatisation des points de collecte, ce qui  permet de :<\/strong><br \/>- r\u00e9duire consid\u00e9rablement les co\u00fbts de livraison,<br \/>- et de remise au client.<\/span><\/h5><h5><span style=\"font-weight: 400;\"><strong>2. La consolidation des flux et la suppression des derniers m\u00e8tres de livraison, ce qui :\u00a0<\/strong><br \/>- rend la livraison moins co\u00fbteuse,<br \/>- et r\u00e9duit le nombre de v\u00e9hicules utilis\u00e9s.<\/span><\/h5><h5><span style=\"font-weight: 400;\"><strong>3. La cr\u00e9ation d\u2019un r\u00e9seau universel<\/strong><br \/>- mutualis\u00e9 avec plusieurs partenaires retailers, nous permettant d\u2019augmenter l'accessibilit\u00e9 pour  les consommateurs. La densit\u00e9 et la capacit\u00e9  \u00e9lev\u00e9es de notre r\u00e9seau augmenteront \u00e9galement   la disponibilit\u00e9 des slots de remise.\u00a0<br \/>- Et notre ambition est de d\u00e9ployer 100 nouveaux Delipop d\u2019ici 2026, avec une  capacit\u00e9 de 20 000  commandes par jour.<\/span><\/h5><h5><span style=\"font-weight: 400;\"><strong>4. L\u2019utilisation de  notre  r\u00e9seau<\/strong><br \/>- sera principalement bas\u00e9e sur des co\u00fbts variables pour les Retailers.<br \/><\/span><\/h5><h5><strong>5. Et puis enfin, la haute qualit\u00e9 de l\u2019exp\u00e9rience  client unique.<\/strong><\/h5><h3><span style=\"font-weight: 400;\">La technologie est importante<\/span><\/h3><h5><span style=\"font-weight: 400;\">Delipop utilise :<\/span><\/h5><h5><span style=\"font-weight: 400;\">- des machines automatiques d\u00e9velopp\u00e9es par Retail Robotics selon nos pr\u00e9conisations avec une interface client simplifi\u00e9e<br \/>- Et un syst\u00e8me d\u2019information sp\u00e9cialis\u00e9 qui permet de monitorer en temps r\u00e9el l\u2019ensemble des slots\/emplacements disponibles sur l\u2019ensemble du r\u00e9seau Delipop<\/span><\/h5><h5><span style=\"font-weight: 400;\">Le syst\u00e8me de robotisation interne \u00e0 tr\u00e8s forte cadence permet de mettre \u00e0 disposition un panier en 15 secondes et une commande type en 1 minute et 30 secondes tout en servant 3 clients simultan\u00e9ment.<\/span><\/h5><h5><span style=\"font-weight: 400;\">La capacit\u00e9 des premi\u00e8res machines se situe entre 60 et 100 commandes par jour. Les suivantes auront m\u00eame une capacit\u00e9 de 100 \u00e0 250 commandes par jour, ce qui nous permettra de servir davantage de clients.<\/span><\/h5><h5><span style=\"font-weight: 400;\">Nos points de proximit\u00e9 restent totalement s\u00e9curis\u00e9s et encadr\u00e9s par un digicode d\u2019acc\u00e8s, des cam\u00e9ras et un centre d\u2019appels disponible \u00e0 tout moment via l\u2019interface client ou par t\u00e9l\u00e9phone.<\/span><\/h5><h3>L'\u00e9cologie est vitale<\/h3><h5 class=\"translation-block\"><span style=\"font-weight: 400\">Gr\u00e2ce \u00e0 la consolidation des commandes, nous utilisons 10 fois moins de camions que lors de la livraison traditionnelle pour livrer le m\u00eame nombre de commandes.<br \/>\nCela se traduit par une diminution significative du trafic, des \u00e9missions de CO2 r\u00e9duites et un air plus pur en ville.<br \/>\nNous encourageons \u00e9galement les consommateurs \u00e0 venir chercher leurs commandes sans utiliser de voiture. \nNous voyons Delipop comme une infrastructure du futur :<br \/>\n- cr\u00e9er des zones vertes dans les villes<br \/>\n- et faciliter le concept de #lavilleduquartd\u2019heure.<\/span><\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-88ad1e6 elementor-section-height-min-height elementor-section-stretched pm0 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"88ad1e6\" data-element_type=\"section\" id=\"e-grocery-business\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4289a1a\" data-id=\"4289a1a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bbcb7d8 elementor-widget elementor-widget-heading\" data-id=\"bbcb7d8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nos partenaires<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d8026a elementor-align-center elementor-mobile-align-justify btn-primary-dark elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"3d8026a\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/fr\/contact\/?subject_id=4\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Parlons des possibilit\u00e9s \u2192<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fe95866 elementor-section-stretched elementor-section-height-min-height startAnimation elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"fe95866\" data-element_type=\"section\" id=\"report\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-46bfce1\" data-id=\"46bfce1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d90d628 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"d90d628\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c3eb5cd showText\" data-id=\"c3eb5cd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b85e394 elementor-widget elementor-widget-heading\" data-id=\"b85e394\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default translation-block\">La r\u00e9volution verte du dernier kilom\u00e8tre<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f79a231 elementor-widget-tablet__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"f79a231\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Delipop a publi\u00e9 le rapport \u00ab Une logistique durable du dernier kilom\u00e8tre pour les courses alimentaires, exemple d\u2019application dans le Grand Paris \u00bb , qui pr\u00e9sente un aper\u00e7u de la r\u00e9volution verte dans les villes fran\u00e7aises.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77d1a87 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"77d1a87\" data-element_type=\"widget\" data-no-translation=\"\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>.elementor-element-77d1a87{display:none !important}<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e43044c elementor-align-center elementor-widget elementor-widget-button\" data-id=\"e43044c\" data-element_type=\"widget\" data-no-translation=\"\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"http:\/\/www.rapport-durabilite.delipop.fr\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Cliquez ici pour plus de d\u00e9tails<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-728b6bc forAnimation\" data-id=\"728b6bc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fce29ad slideInRight elementor-widget elementor-widget-image\" data-id=\"fce29ad\" data-element_type=\"widget\" id=\"heart\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/elementor\/thumbs\/icon4-pnxctspgk2ze3p4ly1kc4oba5zsnayxk8wny725d0c.png\" title=\"icon4\" alt=\"icon4\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8b72120 slideInRight elementor-widget elementor-widget-image\" data-id=\"8b72120\" data-element_type=\"widget\" id=\"pointing\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/elementor\/thumbs\/icon5-pnxctspgx8m5g4dfyw7y7d7sd1iviqax8ee5flc0wk.png\" title=\"icon5\" alt=\"icon5\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-091fe6f slideInRight elementor-widget elementor-widget-image\" data-id=\"091fe6f\" data-element_type=\"widget\" data-no-translation=\"\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>.elementor-element-091fe6f{display:none !important}<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-95af882 slideInRight elementor-widget elementor-widget-image\" data-id=\"95af882\" data-element_type=\"widget\" data-no-translation=\"\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"684\" src=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/04\/1645-tablet-flat-FR2a-768x684.png\" class=\"attachment-medium_large size-medium_large wp-image-6908\" alt=\"\" srcset=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/04\/1645-tablet-flat-FR2a-768x684.png 768w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/04\/1645-tablet-flat-FR2a-300x267.png 300w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/04\/1645-tablet-flat-FR2a-1024x912.png 1024w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/04\/1645-tablet-flat-FR2a-13x12.png 13w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/04\/1645-tablet-flat-FR2a.png 1301w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/04\/1645-tablet-flat-FR2a-300x267@2x.png 600w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/04\/1645-tablet-flat-FR2a-13x12@2x.png 26w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-91e7329 elementor-section-stretched elementor-section-height-min-height elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"91e7329\" data-element_type=\"section\" id=\"world\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-22c4192\" data-id=\"22c4192\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b84eca1 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"b84eca1\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e9727ae forAnimation\" data-id=\"e9727ae\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-36961ec elementor-widget elementor-widget-image\" data-id=\"36961ec\" data-element_type=\"widget\" id=\"tree\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"693\" height=\"903\" src=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/01\/Mask-Group-31a@2x.png\" class=\"attachment-medium_large size-medium_large wp-image-5052\" alt=\"\" srcset=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/01\/Mask-Group-31a@2x.png 693w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/01\/Mask-Group-31a@2x-230x300.png 230w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/01\/Mask-Group-31a@2x-9x12.png 9w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/01\/Mask-Group-31a@2x-230x300@2x.png 460w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/01\/Mask-Group-31a@2x-9x12@2x.png 18w\" sizes=\"(max-width: 693px) 100vw, 693px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b879fe elementor-widget elementor-widget-image\" data-id=\"2b879fe\" data-element_type=\"widget\" id=\"bee-right\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"214\" src=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/01\/Group-1364@2x.png\" class=\"attachment-medium_large size-medium_large wp-image-5051\" alt=\"\" srcset=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/01\/Group-1364@2x.png 200w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/01\/Group-1364@2x-11x12.png 11w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/01\/Group-1364@2x-11x12@2x.png 22w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d513879 elementor-widget elementor-widget-image\" data-id=\"d513879\" data-element_type=\"widget\" id=\"bee-left\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"214\" src=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/01\/Group-1365@2x.png\" class=\"attachment-medium_large size-medium_large wp-image-5050\" alt=\"\" srcset=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/01\/Group-1365@2x.png 200w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/01\/Group-1365@2x-11x12.png 11w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/01\/Group-1365@2x-11x12@2x.png 22w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f7fc8a1\" data-id=\"f7fc8a1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-636b1a8 elementor-widget elementor-widget-heading\" data-id=\"636b1a8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nous sommes<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af7ae27 elementor-widget elementor-widget-heading\" data-id=\"af7ae27\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00c9cologiques<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-07b4499 elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"07b4499\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Livrer \u00e0 domicile et se rendre dans des supermarch\u00e9s \u00e9loign\u00e9s g\u00e9n\u00e8rent beaucoup de circulation. Gr\u00e2ce \u00e0 Delipop, nous donnons \u00e0 nos villes un peu de r\u00e9pit et r\u00e9duisons les \u00e9missions de CO2.<br \/>\u00a0<span style=\"color: var(--nv-text-color); letter-spacing: var(--bodyLetterSpacing); text-transform: var(--bodyTextTransform);\">Notre r\u00e9seau de points de retrait :<\/span><\/p><ul><li>Nous r\u00e9duisons les \u00e9missions de gaz \u00e0 effet de serre de 77% par commande par rapport \u00e0 la livraison \u00e0 domicile, et de 92% par rapport aux achats en hypermarch\u00e9.<\/li><li>Les kilom\u00e8tres parcourus par commande sont r\u00e9duits de 92,5% par rapport \u00e0 la livraison \u00e0 domicile, et de 98,5% par rapport aux achats en hypermarch\u00e9.<\/li><li>De plus, notre r\u00e9seau permet d\u2019\u00e9conomiser plus d\u2019\u00e9missions de CO2 que ce qui est absorb\u00e9 par 500 000 arbres \u00e0 Paris.<\/li><li>Nous offrons \u00e9galement la possibilit\u00e9 de r\u00e9cup\u00e9rer vos courses \u00e0 pied ou \u00e0 v\u00e9lo, favorisant ainsi des modes de transport durables.<\/li><li>Accompagne les villes dans la cr\u00e9ation de zones vertes pour leurs habitants.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c80438c elementor-align-justify elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"c80438c\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Learn more about our positive influence \u2192<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-84c22e9 elementor-align-justify btn-primary-light elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"84c22e9\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Regardez <i style=\"font-size:30px;vertical-align:middle;line-height:0;margin-left:10px;\" class=\"fas fa-eye\"><\/i><\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a4ee1d0 elementor-section-height-min-height elementor-section-stretched elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"a4ee1d0\" data-element_type=\"section\" id=\"urban-zone\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e7d9794\" data-id=\"e7d9794\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-cbdf151 elementor-section-full_width elementor-reverse-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"cbdf151\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-66c99e9\" data-id=\"66c99e9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0fde4d7 elementor-widget elementor-widget-heading\" data-id=\"0fde4d7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">La circulation dans les villes<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0416dd0 elementor-widget elementor-widget-heading\" data-id=\"0416dd0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">est r\u00e9invent\u00e9e<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2615e64 elementor-widget elementor-widget-text-editor\" data-id=\"2615e64\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Moins de voitures sur la chauss\u00e9e, c'est plus d'espace pour les amateurs de v\u00e9lo et de balade.<\/p><p>En r\u00e9duisant les livraisons \u00e0 domicile des courses, on r\u00e9duit \u00e9galement le besoin de v\u00e9hicules. Gr\u00e2ce \u00e0 nous, la ville devient un terrain de jeu encore plus sympa pour les pi\u00e9tons et les cyclistes !<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7517593 animateHole biggerHole\" data-id=\"7517593\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ba7620 animate-img elementor-widget elementor-widget-image\" data-id=\"3ba7620\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/elementor\/thumbs\/Group-16273@2x-ps55wzq5luk3op0i70cng03gk195k9um2dfprf979i.png\" title=\"Group 16273@2x\" alt=\"Group 16273@2x\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e22720 map elementor-widget__width-auto elementor-absolute elementor-widget elementor-widget-image\" data-id=\"2e22720\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/elementor\/thumbs\/Image-29@2x-qg0q5jfp4progr32sfefmvufuyfg56loczzsyg0g5i.png\" title=\"Image 29@2x\" alt=\"Image 29@2x\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f712c5c map2 elementor-widget__width-auto elementor-absolute elementor-widget elementor-widget-image\" data-id=\"f712c5c\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/elementor\/thumbs\/Image-29@2x-qg0q5jfp4progr32sfefmvufuyfg56loczzsyg0g5i.png\" title=\"Image 29@2x\" alt=\"Image 29@2x\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-87c8e4b map3 elementor-widget__width-auto elementor-absolute elementor-widget elementor-widget-image\" data-id=\"87c8e4b\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/elementor\/thumbs\/Image-29@2x-qg0q5jfp4progr32sfefmvufuyfg56loczzsyg0g5i.png\" title=\"Image 29@2x\" alt=\"Image 29@2x\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-500e8d8 elementor-section-height-min-height elementor-section-stretched elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"500e8d8\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1289111\" data-id=\"1289111\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ad8ec9c elementor-section-stretched elementor-section-full_width elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"ad8ec9c\" data-element_type=\"section\" id=\"rent-us-space\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e8101b8\" data-id=\"e8101b8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1a0d26b elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"1a0d26b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9f4aa6d\" data-id=\"9f4aa6d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-96a6dda elementor-widget elementor-widget-heading\" data-id=\"96a6dda\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Louez-nous<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cba3326 elementor-widget elementor-widget-heading\" data-id=\"cba3326\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">votre local!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f75abd7 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"f75abd7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Vous \u00eates propri\u00e9taire d'un local \u00e0 Paris ou en Ile-de-France et vous souhaitez trouver un partenaire fiable et durable qui vous aidera \u00e0 le valoriser?<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-36fca04 elementor-widget elementor-widget-text-editor\" data-id=\"36fca04\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nous recherchons<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c8c176 elementor-widget elementor-widget-text-editor\" data-id=\"6c8c176\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"su-row\"><div class=\"su-column su-column-size-1-2\"><div class=\"su-column-inner su-u-clearfix su-u-trim\"><i class=\"fa fa-check\"><\/i> Un local d\u2019au moins 40 m2<br\/>\n<i class=\"fa fa-check\"><\/i> D\u2019au moins 2,95 m de hauteur<br\/>\n<i class=\"fa fa-check\"><\/i> De plus de 10,8 m de long<\/div><\/div><div class=\"su-column su-column-size-1-2\"><div class=\"su-column-inner su-u-clearfix su-u-trim\"> <i class=\"fa fa-check\"><\/i> De plus de 4 m de large<br\/>\n<i class=\"fa fa-check\"><\/i> Situ\u00e9 dans un quartier tr\u00e8s fr\u00e9quent\u00e9<br\/>\n<i class=\"fa fa-check\"><\/i> Facilement accessible <\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b177e7f elementor-align-left elementor-mobile-align-justify btn-primary-dark elementor-widget elementor-widget-button\" data-id=\"b177e7f\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"\/fr\/contact\/?subject_id=2\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Nous contacter \u2192<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-60a51c0\" data-id=\"60a51c0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b8a831 rent-slider elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"1b8a831\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;dots&quot;,&quot;infinite&quot;:&quot;no&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrousel d\u2019images\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 sur 9\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1b8a831\" data-elementor-lightbox-title=\"194 Av de Versailles 75016 Paris\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzkyOCwidXJsIjoiaHR0cHM6XC9cL2RlbGlwb3AuZndjaC5wbFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMTJcLzIwMjEwOTIwXzE1MjYzMl9meHRvdGVtMi5qcGciLCJzbGlkZXNob3ciOiIxYjhhODMxIn0%3D\" href=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2021\/12\/20210920_152632_fxtotem2.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2021\/12\/20210920_152632_fxtotem2-930x620.jpg\" alt=\"194 Av de Versailles 75016 Paris\" \/><figcaption class=\"elementor-image-carousel-caption\">194 Av de Versailles 75016 Paris<\/figcaption><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 sur 9\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1b8a831\" data-elementor-lightbox-title=\"194 Av de Versailles 75016 Paris\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjM1NywidXJsIjoiaHR0cHM6XC9cL2RlbGlwb3AuZndjaC5wbFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMTBcLzIwMjEwOTIxXzEzMDk1Ml9meDIucG5nIiwic2xpZGVzaG93IjoiMWI4YTgzMSJ9\" href=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2021\/10\/20210921_130952_fx2.png\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2021\/10\/20210921_130952_fx2-930x620.png\" alt=\"194 Av de Versailles 75016 Paris\" \/><figcaption class=\"elementor-image-carousel-caption\">194 Av de Versailles 75016 Paris<\/figcaption><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 sur 9\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1b8a831\" data-elementor-lightbox-title=\"194 Av de Versailles 75016 Paris\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjM1OCwidXJsIjoiaHR0cHM6XC9cL2RlbGlwb3AuZndjaC5wbFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMTBcLzIwMjEwOTIxXzEzMTExNl9meDIucG5nIiwic2xpZGVzaG93IjoiMWI4YTgzMSJ9\" href=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2021\/10\/20210921_131116_fx2.png\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2021\/10\/20210921_131116_fx2-930x620.png\" alt=\"194 Av de Versailles 75016 Paris\" \/><figcaption class=\"elementor-image-carousel-caption\">194 Av de Versailles 75016 Paris<\/figcaption><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 sur 9\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1b8a831\" data-elementor-lightbox-title=\"194 Av de Versailles 75016 Paris\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjM1OSwidXJsIjoiaHR0cHM6XC9cL2RlbGlwb3AuZndjaC5wbFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMTBcLzIwMjEwOTIxXzEzMTEzMF9meDIucG5nIiwic2xpZGVzaG93IjoiMWI4YTgzMSJ9\" href=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2021\/10\/20210921_131130_fx2.png\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2021\/10\/20210921_131130_fx2-930x620.png\" alt=\"194 Av de Versailles 75016 Paris\" \/><figcaption class=\"elementor-image-carousel-caption\">194 Av de Versailles 75016 Paris<\/figcaption><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 sur 9\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1b8a831\" data-elementor-lightbox-title=\"194 Av de Versailles 75016 Paris\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjM2MCwidXJsIjoiaHR0cHM6XC9cL2RlbGlwb3AuZndjaC5wbFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMTBcLzIwMjEwOTIxXzEzMTMyOF9meDIucG5nIiwic2xpZGVzaG93IjoiMWI4YTgzMSJ9\" href=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2021\/10\/20210921_131328_fx2.png\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2021\/10\/20210921_131328_fx2-930x620.png\" alt=\"194 Av de Versailles 75016 Paris\" \/><figcaption class=\"elementor-image-carousel-caption\">194 Av de Versailles 75016 Paris<\/figcaption><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 sur 9\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1b8a831\" data-elementor-lightbox-title=\"194 Av de Versailles 75016 Paris\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjM2MSwidXJsIjoiaHR0cHM6XC9cL2RlbGlwb3AuZndjaC5wbFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMTBcLzIwMjEwOTIxXzIxMTIyM19meDIuanBnIiwic2xpZGVzaG93IjoiMWI4YTgzMSJ9\" href=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2021\/10\/20210921_211223_fx2.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2021\/10\/20210921_211223_fx2-900x620.jpg\" alt=\"194 Av de Versailles 75016 Paris\" \/><figcaption class=\"elementor-image-carousel-caption\">194 Av de Versailles 75016 Paris<\/figcaption><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 sur 9\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1b8a831\" data-elementor-lightbox-title=\"IMG_4849\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Njg5OSwidXJsIjoiaHR0cHM6XC9cL2RlbGlwb3AuZndjaC5wbFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDRcL0lNR180ODQ5LXNjYWxlZC5qcGciLCJzbGlkZXNob3ciOiIxYjhhODMxIn0%3D\" href=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/04\/IMG_4849-scaled.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/04\/IMG_4849-930x620.jpg\" alt=\"2 rue d&#039;Orsel 75018 Paris\" \/><figcaption class=\"elementor-image-carousel-caption\">2 rue d'Orsel 75018 Paris<\/figcaption><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 sur 9\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1b8a831\" data-elementor-lightbox-title=\"IMG_4845\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Njg5OCwidXJsIjoiaHR0cHM6XC9cL2RlbGlwb3AuZndjaC5wbFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDRcL0lNR180ODQ1LXNjYWxlZC5qcGciLCJzbGlkZXNob3ciOiIxYjhhODMxIn0%3D\" href=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/04\/IMG_4845-scaled.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/04\/IMG_4845-930x620.jpg\" alt=\"2 rue d&#039;Orsel 75018 Paris\" \/><figcaption class=\"elementor-image-carousel-caption\">2 rue d'Orsel 75018 Paris<\/figcaption><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 sur 9\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1b8a831\" data-elementor-lightbox-title=\"bezons_www\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Njg5NCwidXJsIjoiaHR0cHM6XC9cL2RlbGlwb3AuZndjaC5wbFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDRcL2Jlem9uc193d3ctc2NhbGVkLmpwZyIsInNsaWRlc2hvdyI6IjFiOGE4MzEifQ%3D%3D\" href=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/04\/bezons_www-scaled.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2022\/04\/bezons_www-930x620.jpg\" alt=\"ZAC Coeur de Ville 95870 Bezons\" \/><figcaption class=\"elementor-image-carousel-caption\">ZAC Coeur de Ville 95870 Bezons<\/figcaption><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a2d9cd elementor-align-center elementor-mobile-align-justify elementor-hidden-desktop elementor-hidden-tablet btn-primary-dark elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"7a2d9cd\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contact us<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-76bb35c elementor-section-height-min-height elementor-section-stretched pm0 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"76bb35c\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-56a7301\" data-id=\"56a7301\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-992c422 elementor-widget elementor-widget-heading\" data-id=\"992c422\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Take the first step<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73cb47e elementor-widget elementor-widget-heading\" data-id=\"73cb47e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">to successful partnership<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fccd922 elementor-section-height-min-height elementor-section-stretched pm0 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"fccd922\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1c957b3\" data-id=\"1c957b3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-755446d elementor-widget elementor-widget-heading\" data-id=\"755446d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">AVEZ-VOUS DES QUESTIONS<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8e2c5cf elementor-widget elementor-widget-heading\" data-id=\"8e2c5cf\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Consultez notre FAQ<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3230f2f elementor-tabs-alignment-stretch faq-section elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"3230f2f\" data-element_type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-5261\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-5261\" aria-expanded=\"false\">I want to rent my space for delipop<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-5262\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-5262\" aria-expanded=\"false\">Je repr\u00e9sente un magasin d\u2019alimentation en ligne<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-5263\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-5263\" aria-expanded=\"false\">Je veux rejoindre l'\u00e9quipe Delipop<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-5261\" aria-expanded=\"false\">I want to rent my space for delipop<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-5261\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-5261\" tabindex=\"0\" hidden=\"false\"><div class=\"su-accordion su-u-trim\">\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus\" data-scroll-offset=\"0\" data-anchor-in-url=\"no\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span>Do Delipop machines generate noise that could disturb the neighbours?<\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">At vero eos et accusamus et iusto odio dignissimos ducimus qui blanditiis praesentium voluptatum deleniti atque corrupti quos dolores et quas molestias excepturi sint occaecati cupiditate non provident, similique sunt in culpa qui officia deserunt mollitia animi, id est laborum et dolorum fuga. <\/div><\/div>\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus su-spoiler-closed\" data-scroll-offset=\"0\" data-anchor-in-url=\"no\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span>How do you prevent the devastation of your pick-up points and machines?<\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">At vero eos et accusamus et iusto odio dignissimos ducimus qui blanditiis praesentium voluptatum deleniti atque corrupti quos dolores et quas molestias excepturi sint occaecati cupiditate non provident, similique sunt in culpa qui officia deserunt mollitia animi, id est laborum et dolorum fuga. <\/div><\/div>\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus su-spoiler-closed\" data-scroll-offset=\"0\" data-anchor-in-url=\"no\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span>Et harum quidem rerum facilis est et expedita distinctio. Nam libero tempore?<\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">At vero eos et accusamus et iusto odio dignissimos ducimus qui blanditiis praesentium voluptatum deleniti atque corrupti quos dolores et quas molestias excepturi sint occaecati cupiditate non provident, similique sunt in culpa qui officia deserunt mollitia animi, id est laborum et dolorum fuga. <\/div><\/div>\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus su-spoiler-closed\" data-scroll-offset=\"0\" data-anchor-in-url=\"no\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span>Et harum quidem rerum facilis est et expedita distinctio. Nam libero tempore?<\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">At vero eos et accusamus et iusto odio dignissimos ducimus qui blanditiis praesentium voluptatum deleniti atque corrupti quos dolores et quas molestias excepturi sint occaecati cupiditate non provident, similique sunt in culpa qui officia deserunt mollitia animi, id est laborum et dolorum fuga. <\/div><\/div>\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus su-spoiler-closed\" data-scroll-offset=\"0\" data-anchor-in-url=\"no\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span>Et harum quidem rerum facilis est et expedita distinctio. Nam libero tempore?<\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">At vero eos et accusamus et iusto odio dignissimos ducimus qui blanditiis praesentium voluptatum deleniti atque corrupti quos dolores et quas molestias excepturi sint occaecati cupiditate non provident, similique sunt in culpa qui officia deserunt mollitia animi, id est laborum et dolorum fuga. <\/div><\/div>\n<\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-5262\" aria-expanded=\"false\">Je repr\u00e9sente un magasin d\u2019alimentation en ligne<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-5262\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-5262\" tabindex=\"0\" hidden=\"hidden\"><div class=\"su-accordion su-u-trim\">\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus\" data-scroll-offset=\"0\" data-anchor-in-url=\"no\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span>Do Delipop machines generate noise that could disturb the neighbours?<\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">At vero eos et accusamus et iusto odio dignissimos ducimus qui blanditiis praesentium voluptatum deleniti atque corrupti quos dolores et quas molestias excepturi sint occaecati cupiditate non provident, similique sunt in culpa qui officia deserunt mollitia animi, id est laborum et dolorum fuga. <\/div><\/div>\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus su-spoiler-closed\" data-scroll-offset=\"0\" data-anchor-in-url=\"no\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span>How do you prevent the devastation of your pick-up points and machines?<\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">At vero eos et accusamus et iusto odio dignissimos ducimus qui blanditiis praesentium voluptatum deleniti atque corrupti quos dolores et quas molestias excepturi sint occaecati cupiditate non provident, similique sunt in culpa qui officia deserunt mollitia animi, id est laborum et dolorum fuga. <\/div><\/div>\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus su-spoiler-closed\" data-scroll-offset=\"0\" data-anchor-in-url=\"no\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span>Et harum quidem rerum facilis est et expedita distinctio. Nam libero tempore?<\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">At vero eos et accusamus et iusto odio dignissimos ducimus qui blanditiis praesentium voluptatum deleniti atque corrupti quos dolores et quas molestias excepturi sint occaecati cupiditate non provident, similique sunt in culpa qui officia deserunt mollitia animi, id est laborum et dolorum fuga. <\/div><\/div>\n<\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-5263\" aria-expanded=\"false\">Je veux rejoindre l'\u00e9quipe Delipop<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-5263\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-5263\" tabindex=\"0\" hidden=\"hidden\"><div class=\"su-accordion su-u-trim\">\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus\" data-scroll-offset=\"0\" data-anchor-in-url=\"no\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span>Do Delipop machines generate noise that could disturb the neighbours?<\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">At vero eos et accusamus et iusto odio dignissimos ducimus qui blanditiis praesentium voluptatum deleniti atque corrupti quos dolores et quas molestias excepturi sint occaecati cupiditate non provident, similique sunt in culpa qui officia deserunt mollitia animi, id est laborum et dolorum fuga. <\/div><\/div>\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus su-spoiler-closed\" data-scroll-offset=\"0\" data-anchor-in-url=\"no\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span>How do you prevent the devastation of your pick-up points and machines?<\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">At vero eos et accusamus et iusto odio dignissimos ducimus qui blanditiis praesentium voluptatum deleniti atque corrupti quos dolores et quas molestias excepturi sint occaecati cupiditate non provident, similique sunt in culpa qui officia deserunt mollitia animi, id est laborum et dolorum fuga. <\/div><\/div>\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus su-spoiler-closed\" data-scroll-offset=\"0\" data-anchor-in-url=\"no\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span>Et harum quidem rerum facilis est et expedita distinctio. Nam libero tempore?<\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">At vero eos et accusamus et iusto odio dignissimos ducimus qui blanditiis praesentium voluptatum deleniti atque corrupti quos dolores et quas molestias excepturi sint occaecati cupiditate non provident, similique sunt in culpa qui officia deserunt mollitia animi, id est laborum et dolorum fuga. <\/div><\/div>\n<\/div><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Be part of a revolution in e-grocery delivery Sustainability \u2192 Career \u2192 JOIN US ON THE JOURNEY AND VISIT THE 1ST EVER DELIPOP POINT Experience the first robotic network of points for collecting e-grocery orders. \/wp-content\/uploads\/2021\/10\/Delipop-Paris-Oppening-En+Lower_Thirds+Subtitles-1.mp4\/wp-content\/uploads\/2021\/10\/Delipop-Paris-Oppening-Fr+Lower_Thirds+Subtitles-1.mp4 DELIPOP IS A MULTIBRAND PICK UP NETWORK discover advantages of our solution: Be part of a revolution in e-grocery&hellip;&nbsp;<a href=\"https:\/\/delipop.fwch.pl\/fr\/company\/\" class=\"\" rel=\"bookmark\">Lire la suite &raquo;<span class=\"screen-reader-text\">Entreprise<\/span><\/a><\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/template-pagebuilder-full-width.php","meta":{"inline_featured_image":false,"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"_links":{"self":[{"href":"https:\/\/delipop.fwch.pl\/fr\/wp-json\/wp\/v2\/pages\/784"}],"collection":[{"href":"https:\/\/delipop.fwch.pl\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/delipop.fwch.pl\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/delipop.fwch.pl\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/delipop.fwch.pl\/fr\/wp-json\/wp\/v2\/comments?post=784"}],"version-history":[{"count":771,"href":"https:\/\/delipop.fwch.pl\/fr\/wp-json\/wp\/v2\/pages\/784\/revisions"}],"predecessor-version":[{"id":8154,"href":"https:\/\/delipop.fwch.pl\/fr\/wp-json\/wp\/v2\/pages\/784\/revisions\/8154"}],"wp:attachment":[{"href":"https:\/\/delipop.fwch.pl\/fr\/wp-json\/wp\/v2\/media?parent=784"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}