{"id":5201,"date":"2021-10-26T13:53:00","date_gmt":"2021-10-26T11:53:00","guid":{"rendered":"https:\/\/delipop.com\/?p=5201"},"modified":"2022-02-03T14:04:28","modified_gmt":"2022-02-03T13:04:28","slug":"delipop-network-as-an-urban-alternative-to-instant-delivery","status":"publish","type":"post","link":"https:\/\/delipop.fwch.pl\/fr\/2021\/10\/26\/delipop-network-as-an-urban-alternative-to-instant-delivery\/","title":{"rendered":"Le r\u00e9seau Delipop comme alternative urbaine \u00e0 la livraison instantan\u00e9e"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"5201\" class=\"elementor elementor-5201\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6066bdb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6066bdb\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-eb113f3\" data-id=\"eb113f3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-07b5eb1 elementor-widget elementor-widget-text-editor\" data-id=\"07b5eb1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>\"L'efficacit\u00e9 de l'agr\u00e9gation des commandes, de l'automatisation du service et de la mise en place d'un r\u00e9seau de sites multi-d\u00e9taillants se traduit par des co\u00fbts d'ex\u00e9cution inf\u00e9rieurs \u00e0 ceux de la livraison traditionnelle et des services de retrait comparables \" - merci \u00e0 Jeff Wells d'avoir couvert sur Grocery Dive la fa\u00e7on dont le r\u00e9seau pratique click-and-collect Delipop et la technologie de Retail Robotics changent l'avenir de l\u2019e-commerce alimentaire et du march\u00e9 de d\u00e9tail.\u00a0<\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8ae43be elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8ae43be\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ebde52a\" data-id=\"ebde52a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-55ff3ea elementor-widget elementor-widget-image\" data-id=\"55ff3ea\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"130\" src=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2021\/10\/News.Grocery-Dive-768x130.png\" class=\"attachment-medium_large size-medium_large wp-image-5206\" alt=\"\" srcset=\"https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2021\/10\/News.Grocery-Dive-768x130.png 768w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2021\/10\/News.Grocery-Dive-300x51.png 300w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2021\/10\/News.Grocery-Dive-1024x174.png 1024w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2021\/10\/News.Grocery-Dive-1536x260.png 1536w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2021\/10\/News.Grocery-Dive-18x3.png 18w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2021\/10\/News.Grocery-Dive.png 2048w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2021\/10\/News.Grocery-Dive-300x51@2x.png 600w, https:\/\/delipop.fwch.pl\/wp-content\/uploads\/2021\/10\/News.Grocery-Dive-18x3@2x.png 36w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e12ad4 elementor-widget elementor-widget-spacer\" data-id=\"6e12ad4\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4ba0905 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4ba0905\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7ce0cd4\" data-id=\"7ce0cd4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fd09939 elementor-widget elementor-widget-text-editor\" data-id=\"fd09939\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Voici quelques citations choisies comme accroche de l'article :<\/span><\/p><p><i><span style=\"font-weight: 400;\">\"Cette agr\u00e9gation des commandes par des passages r\u00e9guliers est une partie de l'\u00e9quation de l'efficacit\u00e9 que Delipop vend aux d\u00e9taillants. Un autre \u00e9l\u00e9ment est le syst\u00e8me robotique, qui peut contenir un grand nombre de commandes de produits alimentaires dans un espace relativement restreint\",<\/span><\/i><span style=\"font-weight: 400;\"> explique Marek Piotrowski, CMO de Delipop et partenaire de Retail Robotics.\u00a0<\/span><\/p><p><i><span style=\"font-weight: 400;\">\"L'accent mis sur une s\u00e9lection plus large, des marques de d\u00e9tail bien connues et des slots de retrait flexibles peut s\u00e9duire les consommateurs urbains tout aussi bien - sinon mieux - que les entreprises de livraison rapide\",<\/span><\/i><span style=\"font-weight: 400;\"> - dit Neil Lambert, PDG de Delipop UK.<\/span><\/p><p><i><span style=\"font-weight: 400;\">\"Cette capacit\u00e9 de stockage est nettement sup\u00e9rieure \u00e0 celle des lockers traditionnels pour les courses alimentaires. (...) Notre machine est comme un guichet automatique pour les d\u00e9taillants\",<\/span><\/i><span style=\"font-weight: 400;\"> - ajoute Michal Mierzejewski, Chief Business Development Officer chez Retail Robotics.<\/span><\/p><p><span style=\"font-weight: 400;\">Vous pouvez lire l'article ici : <\/span><a href=\"https:\/\/www.grocerydive.com\/news\/european-pickup-depot-delipop-launches-an-urban-alternative-to-instant-deli\/608045\/\"><span style=\"font-weight: 400;\">https:\/\/www.grocerydive.com\/news\/european-pickup-depot-delipop-launches-an-urban-alternative-to-instant-deli\/608045\/<\/span><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Lire en<\/span> <span class=\"rt-time\"> &lt;\u00a01<\/span> <span class=\"rt-label rt-postfix\">minute<\/span><\/span>\u201cThe efficiency of aggregating orders, automating service and building out a network of multi-retailer locations results in lower fulfillment costs than traditional delivery and comparable pickup services\u201d &#8211; thank you Jeff Wells for covering on Grocery Dive how Delipop\u2019s convenient click-and-collect network and technology from Retail Robotics is changing the future of e-grocery and retail&hellip;&nbsp;<a href=\"https:\/\/delipop.fwch.pl\/fr\/2021\/10\/26\/delipop-network-as-an-urban-alternative-to-instant-delivery\/\" class=\"\" rel=\"bookmark\">Lire la suite &raquo;<span class=\"screen-reader-text\">Le r\u00e9seau Delipop comme alternative urbaine \u00e0 la livraison instantan\u00e9e<\/span><\/a><\/p>","protected":false},"author":1,"featured_media":5217,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/delipop.fwch.pl\/fr\/wp-json\/wp\/v2\/posts\/5201"}],"collection":[{"href":"https:\/\/delipop.fwch.pl\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/delipop.fwch.pl\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/delipop.fwch.pl\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/delipop.fwch.pl\/fr\/wp-json\/wp\/v2\/comments?post=5201"}],"version-history":[{"count":14,"href":"https:\/\/delipop.fwch.pl\/fr\/wp-json\/wp\/v2\/posts\/5201\/revisions"}],"predecessor-version":[{"id":5218,"href":"https:\/\/delipop.fwch.pl\/fr\/wp-json\/wp\/v2\/posts\/5201\/revisions\/5218"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/delipop.fwch.pl\/fr\/wp-json\/wp\/v2\/media\/5217"}],"wp:attachment":[{"href":"https:\/\/delipop.fwch.pl\/fr\/wp-json\/wp\/v2\/media?parent=5201"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/delipop.fwch.pl\/fr\/wp-json\/wp\/v2\/categories?post=5201"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/delipop.fwch.pl\/fr\/wp-json\/wp\/v2\/tags?post=5201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}